{"id":5513,"date":"2017-11-11T04:43:48","date_gmt":"2017-11-11T04:43:48","guid":{"rendered":"https:\/\/wpbakery.thembay.com\/puca_wcvendors\/?page_id=3169"},"modified":"2025-02-12T10:31:24","modified_gmt":"2025-02-12T10:31:24","slug":"contact-us-01-2","status":"publish","type":"page","link":"https:\/\/www.glinthair.com\/index.php\/contact-us-01-2\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column css=&#8221;.vc_custom_1510195195671{padding-top: 27px !important;}&#8221;][tbay_title_heading title=&#8221;Contact Us&#8221; style=&#8221;style3&#8243; buttons=&#8221;btn-default btn-outline&#8221; buttons2=&#8221;btn-default btn-outline&#8221; el_class=&#8221;no-bg-title&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-6412\"><form id=\"wpforms-form-6412\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"6412\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/5513\" data-token=\"74daddf70c48cb6167c92126ec2fa648\" data-token-time=\"1778676970\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-hidden\" id=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-6412-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-6412-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"First Name\" aria-errormessage=\"wpforms-6412-field_1-error\" required><label for=\"wpforms-6412-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-6412-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Last Name\" aria-errormessage=\"wpforms-6412-field_1-last-error\" required><label for=\"wpforms-6412-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-6412-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-6412-field_2\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-6412-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"email@gmail.com\" spellcheck=\"false\" aria-errormessage=\"wpforms-6412-field_2-error\" required><\/div><div id=\"wpforms-6412-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-6412-field_3\">Comment or Message<\/label><textarea id=\"wpforms-6412-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-6412-field_3-error\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"6412\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/pages\/5513\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-6412\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.glinthair.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column css=&#8221;.vc_custom_1510195195671{padding-top: 27px !important;}&#8221;][tbay_title_heading title=&#8221;Contact Us&#8221; style=&#8221;style3&#8243; buttons=&#8221;btn-default btn-outline&#8221; buttons2=&#8221;btn-default btn-outline&#8221; el_class=&#8221;no-bg-title&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5513","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/pages\/5513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/comments?post=5513"}],"version-history":[{"count":0,"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/pages\/5513\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.glinthair.com\/index.php\/wp-json\/wp\/v2\/media?parent=5513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}